{"id":2103,"date":"2020-01-03T12:12:06","date_gmt":"2020-01-03T11:12:06","guid":{"rendered":"https:\/\/www.griffbereit-rucksack.de\/?page_id=2103"},"modified":"2023-12-01T12:59:20","modified_gmt":"2023-12-01T11:59:20","slug":"faq-rucksack-kita","status":"publish","type":"page","link":"https:\/\/www.griffbereit-rucksack.de\/it\/rucksack-kita\/faq-rucksack-kita\/","title":{"rendered":"FAQ Rucksack KiTa"},"content":{"rendered":"<h2>FAQ Rucksack KiTa<\/h2>\n<p>Sia come famiglia interessata, che come specialista pedagogico, genitore mentore o coordinatore del programma: <strong>Qui trover\u00e0 le risposte alle domande pi\u00f9 frequenti.<\/strong><\/p>\n<div class=\"wm-accordion clearfix filterable-simple\" data-active=\"0\" data-mode=\"accordion\"><div class=\"wm-filter\"><ul><li class=\"wm-filter-items-all active\"><a href=\"#\" data-filter=\"*\">All<\/a><\/li><li class=\"wm-filter-items-tag-ElternFamilien\"><a href=\"#\" data-filter=\".tag-ElternFamilien\">Genitori\/famiglie<\/a><\/li><li class=\"wm-filter-items-tag-Elternbegleiterinnen\"><a href=\"#\" data-filter=\".tag-Elternbegleiterinnen\">Consulenti per i genitori<\/a><\/li><li class=\"wm-filter-items-tag-Koordinatorinnen\"><a href=\"#\" data-filter=\".tag-Koordinatorinnen\">Coordinatori<\/a><\/li><li class=\"wm-filter-items-tag-PdagogischeFachkrfte\"><a href=\"#\" data-filter=\".tag-PdagogischeFachkrfte\">Professionisti dell'educazione<\/a><\/li><\/ul><\/div><div class=\"wm-filter-this-simple\">\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Cosa vuole Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WasmchteRucksackKiTa\"><p>L'attenzione si concentra sull'educazione linguistica e familiare generale e multilingue integrata nella vita quotidiana, sostenuta congiuntamente dai genitori\/famiglie e dall'asilo nido.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Chi pu\u00f2 partecipare a Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WerkannanRucksackKiTateilnehmen\"><ul>\n<li>I bambini di et\u00e0 compresa tra i quattro e i sei anni che stanno crescendo multilingue e i loro genitori\/famiglie che vogliono conoscere e sfruttare il potenziale del multilinguismo nei primi anni di vita dei loro figli e l'asilo nido frequentato dal bambino.<\/li>\n<li>Condizione: Il KiTa \u00e8 collegato al programma<\/li>\n<li>Le istituzioni educative che vogliono aprirsi alla diversit\u00e0 orientata alla diversit\u00e0<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Dove si svolge un gruppo Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WofindeteineRucksackKiTa-Gruppestatt\"><p>Il<em> Rucksack KiTa<\/em>-Il gruppo viene offerto in loco presso l'asilo nido partecipante.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Quando mio figlio pu\u00f2 iniziare l'Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WannkannmeinKindmitRucksackKiTastarten\"><p>Si consiglia di iniziare all'inizio dell'anno di scuola materna e dopo la fase di familiarizzazione.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Quando si svolge un gruppo Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WannfindeteineRucksackKiTa-Gruppestatt\"><p>Il<em> Rucksack KiTa<\/em>-Il gruppo si svolge solitamente durante l'anno della scuola materna: una volta alla settimana per circa 9 mesi.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Chi \u00e8 responsabile del programma?<\/h3><div class=\"wm-item-content clearfix WeristfrdasProgrammverantwortlich\"><p><em>Rucksack KiTa<\/em> wird von den Landesweiten Koordinierungsstellen (LaKos) fachlich begleitet. Auch die Gesamtkoordination NRW und bundesweit liegt bei der LaKo.N\u00e4here Informationen finden Sie <a href=\"https:\/\/www.griffbereit-rucksack.de\/it\/ueber-uns\/\"><strong>qui<\/strong><\/a><\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Qual \u00e8 il ruolo dell'asilo nido che offre Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WelcheAufgabenhatdieKiTadieRucksackKiTaanbietet\"><ul>\n<li>Il programma <em>Rucksack KiTa<\/em> fa parte del concetto<\/li>\n<li>Il KiTa o il fornitore del KiTa sono partner di cooperazione del programma nazionale. <em>Rucksack KiTa<\/em><\/li>\n<li>L'asilo nido o il fornitore dell'asilo nido mettono a disposizione i locali per il <em>Rucksack KiTa<\/em>-Pronto per il gruppo<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Quali sono i compiti del team Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WelcheAufgabenhatdasRucksackKiTa-Team\"><ul>\n<li>Educazione linguistica integrata quotidiana in tedesco<\/li>\n<li>Accompagnare e sostenere il plurilinguismo dei bambini<\/li>\n<li>Partenariati educativi partecipativi con i genitori\/famiglie<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-ElternFamilien\"><h3 class=\"wm-item-title tag-ElternFamilien\" data-tags=\"tag-ElternFamilien\" data-tag-names=\"Eltern\/Familien\">Durante il gruppo genitori Rucksack KiTa \u00e8 prevista l'assistenza per i fratelli e le sorelle?<\/h3><div class=\"wm-item-content clearfix IstwhrendderRucksackKiTa-ElterngruppeeineKinderbetreuungfrGeschwisterkindergewhrleistet\"><p>S\u00ec, se partecipano genitori\/famiglie con figli di et\u00e0 inferiore o superiore al gruppo target del programma, l'assistenza ai bambini pu\u00f2 essere fornita presso l'asilo nido.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Elternbegleiter*innen|Koordinator*innen\">Chi \u00e8 responsabile del programma Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WeristfrdasProgrammRucksackKiTaverantwortlich\"><p><em>Rucksack KiTa<\/em> wird von den Landesweiten Koordinierungsstellen (LaKo) fachlich begleitet. Auch die Gesamtkoordination NRW und bundesweit liegt bei der LaKo.N\u00e4here Informationen finden Sie <a href=\"https:\/\/www.griffbereit-rucksack.de\/it\/ueber-uns\/\"><strong>qui<\/strong><\/a>L'attuazione \u00e8 obbligatoria in collaborazione con i centri di integrazione municipali locali (KI) e i partner di cooperazione a livello nazionale (centri di coordinamento statali, centri di coordinamento dei programmi locali e\/o regionali).<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Elternbegleiterinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Elternbegleiterinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Elternbegleiterinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Elternbegleiter*innen\">Chi assumer\u00e0 la guida nell'attuazione del programma?<\/h3><div class=\"wm-item-content clearfix WerbernimmtdieFederfhrungzurDurchfhrungdesProgramms\"><p>I centri di integrazione comunali o i partner di cooperazione a livello nazionale coordinano o sostengono il programma, se necessario anche in collaborazione con altri uffici\/agenzie, e offrono eventi informativi e corsi di formazione.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Elternbegleiter*innen|Koordinator*innen\">Quando pu\u00f2 iniziare il programma?<\/h3><div class=\"wm-item-content clearfix WannkanndasProgrammstarten\"><p>Si consiglia di iniziare all'inizio dell'anno di scuola materna e dopo la fase di familiarizzazione.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Koordinator*innen\">Quali argomenti sono particolarmente adatti ai corsi precursori, introduttivi o di prova?<\/h3><div class=\"wm-item-content clearfix WelcheThemeneignensichbesondersfrVorlufer-Einstiegs-oderSchnupperkurse\"><p>Ingresso in famiglia o in asilo nido, media, esercizio fisico<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte\" data-tags=\"tag-PdagogischeFachkrfte\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte\">Quali sono i KiTas e i centri per le famiglie adatti?<\/h3><div class=\"wm-item-content clearfix WelcheKiTasundFamilienzentrensindgeeignet\"><p>KiTas e centri per le famiglie che<\/p>\n<ul>\n<li>registrare il proprio interesse presso il KI o il partner di cooperazione a livello nazionale o il team di trasferimento federale<\/li>\n<li>disporre di camere sufficienti<\/li>\n<li>mostrare una dimensione di gruppo sufficiente per la formazione di gruppi familiari (almeno 6 famiglie interessate)<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte\" data-tags=\"tag-PdagogischeFachkrfte\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte\">Quali organismi dovrebbero essere coinvolti nella pianificazione del programma fin dall'inizio?<\/h3><div class=\"wm-item-content clearfix WelcheStellensolltenvonAnfanganbeiderProgrammplanungeingebundenwerden\"><p>Consigliato: Ufficio di assistenza ai giovani\/consulenza specializzata e possibili sponsor e donatori.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte\" data-tags=\"tag-PdagogischeFachkrfte\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte\">Chi deve essere collegato in rete per garantire il successo del programma?<\/h3><div class=\"wm-item-content clearfix WersollteimHinblickaufdasGelingendesProgrammsmiteinandervernetztsein\"><ul>\n<li>Centro di integrazione comunale\/partner di cooperazione federale<\/li>\n<li>Ufficio di assistenza ai giovani<\/li>\n<li>Fornitore KiTa\/consulenza specialistica<\/li>\n<li>Gestione e team dell'asilo nido<\/li>\n<li>Consulente per i genitori<\/li>\n<li>Altri partner della rete, ad esempio biblioteche, ecc.<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Koordinator*innen\">Quali sono i passi da compiere prima di attuare il programma nel KiTa?<\/h3><div class=\"wm-item-content clearfix WelcheSchrittesindvorderImplementierungdesProgrammsinderKiTazubeachten\"><ul>\n<li>Chiarimento dei compiti dell'agenzia esecutiva del programma<\/li>\n<li>Chiarimenti sul finanziamento<\/li>\n<li>Accordo di cooperazione tra fornitore\/centro di assistenza diurna e KI\/partner di cooperazione federale<\/li>\n<li>Presentazione del programma, manifestazione di interesse e acquisizione<\/li>\n<li>Qualifica<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Koordinator*innen\">Quali sono i compiti dell'istituzione educativa?<\/h3><div class=\"wm-item-content clearfix WelcheAufgabenhatdieBildungsinstitution\"><ul>\n<li>programma <em>Rucksack KiTa<\/em> agisce come concetto dell'istituzione educativa (offerta integrativa)<\/li>\n<li>Accordo di cooperazione tra KI\/partner di cooperazione a livello nazionale e KiTa\/fornitore del KiTa (definizione degli obiettivi di cooperazione, contributi di cooperazione dei partner, finanze).<\/li>\n<li>Fornisca i locali per il gruppo di genitori\/famiglie (ed eventualmente l'assistenza ai bambini).<\/li>\n<li>Partecipazione alla valutazione annuale<\/li>\n<li>Partecipazione ai programmi di qualificazione<\/li>\n<li>Se applicabile: partecipazione al gruppo di lavoro Griffbereit e zaino sul posto<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Koordinator*innen\">Quali sono i compiti del team Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WelcheAufgabenhatdasRucksackKiTa-Team\"><ul>\n<li>Coordinamento e attuazione di un'educazione linguistica integrata parallelizzata e quotidiana in tedesco, coordinata con il gruppo di genitori\/famiglie.<\/li>\n<li>Accompagnare e sostenere il plurilinguismo dei bambini<\/li>\n<li>Partenariati educativi partecipativi con i genitori\/famiglie<\/li>\n<li>Coordinamento e attuazione di incontri di pianificazione e accordi tra educatori, consulenti per i genitori, (eventualmente AI) in coordinamento con i consulenti per i genitori\/discussione delle richieste dei genitori\/famiglie.<\/li>\n<li>Partecipazione a incontri di scambio e di riflessione in loco<\/li>\n<li>Partecipazione alla valutazione annuale<\/li>\n<li>Partecipazione ai programmi di qualificazione<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Koordinator*innen\">Quali sono i compiti del KI\/partner di cooperazione nazionale?<\/h3><div class=\"wm-item-content clearfix WelcheAufgabenhabendasKIderbundesweiteKooperationspartner\"><ul>\n<li>Presentazione del programma ai fornitori interessati, al team KiTa, ecc.<\/li>\n<li>Coordinamento\/supervisione del programma<\/li>\n<li>Fornitura di materiali<\/li>\n<li>Pubblicit\u00e0 per il programma<\/li>\n<li>Partecipazione e valutazione della valutazione annuale<\/li>\n<li>Qualifica di base dei consulenti ed educatori per i genitori<\/li>\n<li>Ulteriore formazione per i consulenti e gli educatori dei genitori<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte\" data-tags=\"tag-PdagogischeFachkrfte\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte\">Chi \u00e8 responsabile del reclutamento dei partecipanti al programma e quali metodi di reclutamento delle famiglie si sono dimostrati efficaci?<\/h3><div class=\"wm-item-content clearfix WeristfrdieWerbungderTeilnehmerinnendesProgrammsverantwortlichbzwwelcheMethodenderFamilienanwerbunghabensichbewhrt\"><ul>\n<li>L'istituto scolastico fa gi\u00e0 riferimento al programma durante i colloqui di registrazione.<\/li>\n<li>Possibilmente pubblicizzando le comunit\u00e0 di migranti e le MSO e possibilmente in consultazione con il Consiglio per l'integrazione.<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Elternbegleiterinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Elternbegleiterinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Elternbegleiterinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Elternbegleiter*innen\">Quali requisiti devono avere i consulenti genitoriali?<\/h3><div class=\"wm-item-content clearfix WelcheVoraussetzungensolltenElternbegleiterinnenmitbringen\"><ul>\n<li>proprio multilinguismo<\/li>\n<li>Flessibile in termini di tempo e spazio<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Elternbegleiter*innen|Koordinator*innen\">Chi stipula il contratto con il consulente genitoriale?<\/h3><div class=\"wm-item-content clearfix WerschlietdenVertragmitdemrElternbegleiterin\"><ul>\n<li>Il portatore del gruppo Rucksack KiTa<\/li>\n<li>L'ente responsabile del centro diurno<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte\" data-tags=\"tag-PdagogischeFachkrfte\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte\">Chi forma i consulenti per i genitori?<\/h3><div class=\"wm-item-content clearfix WerschultdieElternbegleiterinnen\"><p>AI locale\/partner di cooperazione federale<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Koordinator*innen\">\u00c8 necessaria l'assistenza ai bambini durante il gruppo Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix IstwhrendderRucksackKiTa-GruppeeineKinderbetreuungnotwendig\"><p>S\u00ec, se partecipano genitori\/famiglie con figli di et\u00e0 inferiore o superiore al gruppo target del programma.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-PdagogischeFachkrfte tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tags=\"tag-PdagogischeFachkrfte tag-Koordinatorinnen\" data-tag-names=\"P\u00e4dagogische Fachkr\u00e4fte|Koordinator*innen\">Chi stipula il contratto con il centro di assistenza all'infanzia?<\/h3><div class=\"wm-item-content clearfix WerschlietdenVertragmitderKinderbetreuung\"><p>Vedi punto: Chi stipula il contratto con il consulente genitoriale?<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Chi assumer\u00e0 la guida nell'attuazione del programma Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WerbernimmtdieFederfhrungzurImplementierungdesRucksackKiTa-Programms\"><p>I centri di integrazione comunali o i partner di cooperazione a livello nazionale coordinano o sostengono il programma, se necessario anche in collaborazione con altri uffici\/agenzie, e offrono eventi informativi e corsi di formazione.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Quali sono le istituzioni educative adatte?<\/h3><div class=\"wm-item-content clearfix WelcheBildungsinstitutionensindgeeignet\"><p>Le istituzioni educative che<\/p>\n<ul>\n<li>registrare il proprio interesse presso il KI o il partner di cooperazione a livello nazionale o il team di trasferimento federale<\/li>\n<li>disporre di camere sufficienti<\/li>\n<li>dimensione del gruppo sufficiente per la formazione di <em>Rucksack KiTa<\/em>-Identificare i gruppi (almeno 6 famiglie).<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Chi deve essere collegato in rete per garantire il successo del programma?<\/h3><div class=\"wm-item-content clearfix WersollteimHinblickaufdasGelingendesProgrammsmiteinandervernetztsein\"><ul>\n<li>Centro di integrazione comunale\/partner di cooperazione federale<\/li>\n<li>Ufficio di assistenza ai giovani<\/li>\n<li>Fornitore KiTa\/consulenza specialistica<\/li>\n<li>Gestione e team dell'asilo nido<\/li>\n<li>Consulente per i genitori<\/li>\n<li>Altri partner della rete, ad esempio biblioteche, ecc.<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Chi stipula l'accordo di cooperazione con l'operatore\/centro diurno e gli altri partner?<\/h3><div class=\"wm-item-content clearfix WerschlietdieKooperationsvereinbarungmitdemTrgerderKiTaundweiterenPartnernab\"><p>Das lokale KI oder der bundesweite Kooperationspartner schlie\u00dft die Kooperationsvereinbarung mit dem Tr\u00e4ger\/der KiTa und &#8211; wenn vorgesehen &#8211; mit weiteren Partnern ab.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Cosa dice l'accordo di cooperazione tra il KiTa e il partner di cooperazione KI\/federale?<\/h3><div class=\"wm-item-content clearfix WasstehtinderKooperationsvereinbarungzwischenKiTaundKIbundesweitemKooperationspartner\"><p>L'accordo di cooperazione stabilisce le rispettive responsabilit\u00e0 e le scadenze per la prova d'uso.<em><br \/><\/em><\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">E gli accordi di cooperazione tra LaKI e il partner di cooperazione KI\/federale o il partner di cooperazione KI\/federale e il fornitore KiTa?<\/h3><div class=\"wm-item-content clearfix WiesiehtesmitKooperationsvereinbarungenzwischenLaKIundKIbundesweitemKooperationspartnerbzwKIbundesweitemKooperationspartnerundTrgerKiTaaus\"><p>L'attuazione \u00e8 legata agli accordi di cooperazione.<em>Gli accordi di cooperazione con i fornitori di servizi di assistenza all'infanzia o i centri diurni locali devono essere stipulati su base regionale. \u00a0<br \/><\/em><\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Chi \u00e8 responsabile del reclutamento dei partecipanti al programma e quali metodi di reclutamento dei genitori\/famiglie hanno avuto successo?<\/h3><div class=\"wm-item-content clearfix WeristfrdieWerbungderTeilnehmerinnendesProgrammsverantwortlichbzwwelcheMethodenderEltern-Familienanwerbunghabensichalserfolgreichherausgestellt\"><ul>\n<li>L'istituto scolastico fa gi\u00e0 riferimento al rispettivo programma durante i colloqui di registrazione.<\/li>\n<li>Possibilmente pubblicizzando le comunit\u00e0 di migranti e le MSO e possibilmente in consultazione con il Consiglio per l'integrazione.<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Quali sono i requisiti da soddisfare quando si cerca un consulente per genitori?<\/h3><div class=\"wm-item-content clearfix WelcheVoraussetzungensindbeiderSuchederElternbegleiterinnenzubeachten\"><ul>\n<li>Consulente genitori multilingue<\/li>\n<li>Flessibile in termini di tempo e spazio<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Quali sono i requisiti da soddisfare quando si cerca un consulente per genitori?<\/h3><div class=\"wm-item-content clearfix WelcheVoraussetzungensindbeiderSuchederElternbegleiterinnenzubeachten\"><ul>\n<li>Consulente genitori multilingue<\/li>\n<li>Flessibile in termini di tempo e spazio<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Quali criteri vengono utilizzati per selezionare e determinare il numero di ore per i consulenti genitoriali?<\/h3><div class=\"wm-item-content clearfix NachwelchenKriterienwirdderStundenumfangderElternbegleiterinnenausgewhltundfestgesetzt\"><p>Consigliato:<\/p>\n<ul>\n<li>3-4 ore a settimana: 2 nel gruppo di genitori e 1-2 ore per la preparazione e il follow-up.<\/li>\n<li>Pi\u00f9 tempo per discussioni di scambio\/riflessione<\/li>\n<li>Pi\u00f9 tempo per l'istruzione e la formazione continua<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Quali criteri vengono utilizzati per selezionare e determinare il numero di ore per i consulenti genitoriali?<\/h3><div class=\"wm-item-content clearfix NachwelchenKriterienwirdderStundenumfangderElternbegleiterinnenausgewhltundfestgesetzt\"><p>Consigliato:<\/p>\n<ul>\n<li>3-4 ore a settimana: 2 nel gruppo di genitori e 1-2 ore per la preparazione e il follow-up.<\/li>\n<li>Pi\u00f9 tempo per discussioni di scambio\/riflessione<\/li>\n<li>Pi\u00f9 tempo per l'istruzione e la formazione continua<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Elternbegleiterinnen tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tags=\"tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tag-names=\"Elternbegleiter*innen|Koordinator*innen\">Come vengono retribuiti i consulenti per i genitori e quali sono le scadenze da tenere in considerazione?<\/h3><div class=\"wm-item-content clearfix WiesiehtdieHonorierungderElternbegleiterinnenausundwelcheTerminesinddabeizubercksichtigen\"><p>L'attivit\u00e0 di consulente per i genitori \u00e8 solitamente retribuita. L'LaKo raccoglie i valori medi e fornisce raccomandazioni in base ai tassi di istruzione familiare\/VHS. Tuttavia, la retribuzione pu\u00f2 anche basarsi sull'indennit\u00e0 forfettaria per i formatori o assumere la forma di un mini-lavoro. Esiste anche il caso del rilascio di personale permanente, che sostituisce la retribuzione diretta.<\/p>\n<ul>\n<li>Realizzazione delle lezioni di gruppo<\/li>\n<li>Formazione, perfezionamento professionale<\/li>\n<li>Riunioni di riflessione e pianificazione<\/li>\n<li>Preparazione e follow-up delle offerte<\/li>\n<li>Se applicabile: date del gruppo di lavoro regionale Griffbereit e zaino<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Elternbegleiterinnen tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tags=\"tag-Elternbegleiterinnen tag-Koordinatorinnen\" data-tag-names=\"Elternbegleiter*innen|Koordinator*innen\">Chi forma i consulenti per i genitori?<\/h3><div class=\"wm-item-content clearfix WerschultdieElternbegleiterinnen\"><p>Empfehlenswert:Federf\u00fchrung der Schulung beim lokalen KI\/bundesweiten Kooperationspartner, der sp\u00e4ter die <em>Rucksack KiTa<\/em>-Gruppen begleitet und so von Anfang an ein Ansprechpartner der Elternbegleiter*innen sein kann. Informationen zum Programm vermittelt das lokale KI\/der bundesweite Kooperationspartner.Zu bestimmten Themenschwerpunkten wie z.B. Medienp\u00e4dagogik, Literacy usw. k\u00f6nnen ggf. Referent*innen eingesetzt werden.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Su cosa dovrebbero concentrarsi i corsi di formazione?<\/h3><div class=\"wm-item-content clearfix WelcheSchwerpunktesolltenbeidenSchulungenbeachtetwerden\"><p>Vedere anche: Curriculum nazionale (disponibile per i coordinatori di programmi registrati nell'area download protetta).<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Quali certificati devono essere rilasciati ai consulenti genitoriali?<\/h3><div class=\"wm-item-content clearfix WelcheBescheinigungensinddenElternbegleiterinnenauszuhndigen\"><ul>\n<li>Conferma della qualifica di base EB<\/li>\n<li>Conferma di un'ulteriore qualifica EB<\/li>\n<li>Conferma del periodo di attivit\u00e0 a pagamento EB<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Come si pu\u00f2 organizzare un incontro di scambio\/riflessione tra diversi gruppi Rucksack KiTa?<\/h3><div class=\"wm-item-content clearfix WielsstsicheinAustausch-ReflexionstreffenzwischenverschiedenenRucksackKiTa-Gruppengestalten\"><ul>\n<li>Come parte di un gruppo di lavoro (regionale) Griffbereit e Rucksack sul posto<\/li>\n<li>Nell'ambito di workshop pratici\/qualifiche<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">A quale dimensione del gruppo ha senso finanziare il programma?<\/h3><div class=\"wm-item-content clearfix BeiwelcherGruppenstrkeistdieFinanzierungdesProgrammssinnvoll\"><p>Consigliamo di mantenere le dimensioni del gruppo tra 6 (minimo) e 18 persone.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Koordinatorinnen\"><h3 class=\"wm-item-title tag-Koordinatorinnen\" data-tags=\"tag-Koordinatorinnen\" data-tag-names=\"Koordinator*innen\">Come si presenta il finanziamento a lungo termine?<\/h3><div class=\"wm-item-content clearfix WiesiehteinelangfristigeFinanzierungaus\"><p>Possibilit\u00e0:<\/p>\n<ul>\n<li>Nell'ambito delle conferenze sull'integrazione e l'istruzione dello Stato\/citt\u00e0\/distretto, definizione degli obiettivi di integrazione, in particolare per la promozione linguistica, l'educazione familiare\/adulta e gli effetti di sinergia attraverso i programmi statali e federali (IfKuF, Sprach-Kitas, ecc.).<\/li>\n<li>Accordi locali, budget <em>Rucksack KiTa<\/em> da includere in modo permanente nel bilancio dei rispettivi uffici di assistenza ai giovani\/fondi dei centri per le famiglie.<\/li>\n<li>Una generosa donazione da parte di un'azienda, di una squadra di calcio, ecc.<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Elternbegleiterinnen\"><h3 class=\"wm-item-title tag-Elternbegleiterinnen\" data-tags=\"tag-Elternbegleiterinnen\" data-tag-names=\"Elternbegleiter*innen\">Quante ore dedicano i consulenti genitoriali al loro lavoro?<\/h3><div class=\"wm-item-content clearfix WiehochistderStundenumfangdenElternbegleiterinnenfrihreTtigkeitaufbringen\"><p>Come regola:<\/p>\n<ul>\n<li>3-4 ore a settimana: 2 nel gruppo di genitori e 1-2 ore per la preparazione e il follow-up.<\/li>\n<li>Pi\u00f9 tempo per discussioni di scambio\/riflessione<\/li>\n<li>Pi\u00f9 tempo per l'istruzione e la formazione continua<\/li>\n<\/ul>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Elternbegleiterinnen\"><h3 class=\"wm-item-title tag-Elternbegleiterinnen\" data-tags=\"tag-Elternbegleiterinnen\" data-tag-names=\"Elternbegleiter*innen\">Qual \u00e8 l'obiettivo della formazione?<\/h3><div class=\"wm-item-content clearfix WelcheSchwerpunktewerdenbeiderSchulunggesetzt\"><p>Vedere anche: Qualifica di consulente genitoriale.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"wm-item wm-item-wrap tag-Elternbegleiterinnen\"><h3 class=\"wm-item-title tag-Elternbegleiterinnen\" data-tags=\"tag-Elternbegleiterinnen\" data-tag-names=\"Elternbegleiter*innen\">Quali certificati ricevono i consulenti genitoriali?<\/h3><div class=\"wm-item-content clearfix WelcheBescheinigungenerhaltenElternbegleiterinnen\"><ul>\n<li>Conferma della qualifica di base EB<\/li>\n<li>Conferma di un'ulteriore qualifica EB<\/li>\n<li>Conferma del periodo di attivit\u00e0 a pagamento EB<\/li>\n<\/ul>\n<\/div><\/div>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\n<div class=\"entry-summary\">\nUlteriori informazioni su Rucksack KiTa sono disponibili qui.\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.griffbereit-rucksack.de\/it\/rucksack-kita\/faq-rucksack-kita\/\" class=\"more-link\">Continua a leggere<span class=\"screen-reader-text\"> &ldquo;FAQ Rucksack KiTa&rdquo;<\/span>...<\/a><\/div>\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.griffbereit-rucksack.de\/it\/rucksack-kita\/faq-rucksack-kita\/\" class=\"more-link\">Continua a leggere<span class=\"screen-reader-text\"> &ldquo;FAQ Rucksack KiTa&rdquo;<\/span>...<\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":623,"menu_order":26,"comment_status":"closed","ping_status":"closed","template":"templates\/with-sidebar.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2103","page","type-page","status-publish","hentry","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/pages\/2103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/comments?post=2103"}],"version-history":[{"count":0,"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/pages\/2103\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/pages\/623"}],"wp:attachment":[{"href":"https:\/\/www.griffbereit-rucksack.de\/it\/wp-json\/wp\/v2\/media?parent=2103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}